{"id":673,"date":"2026-08-11T13:37:17","date_gmt":"2026-08-11T11:37:17","guid":{"rendered":"https:\/\/temp.hufak.net\/psychological-counselling\/"},"modified":"2026-08-21T13:43:00","modified_gmt":"2026-08-21T11:43:00","slug":"psychological-counselling","status":"publish","type":"page","link":"https:\/\/temp.hufak.net\/de\/psychological-counselling\/","title":{"rendered":"Psychological Counselling"},"content":{"rendered":"\n<p>Die psychologische Beratung bietet allen Studierenden der Angewandten bei Bedarf vertraulich, anonym und kostenfrei Hilfe durch erfahrene Psychotherapeut*innen. Die Beratung unterst\u00fctzt Studierende unmittelbar bei der Suche nach L\u00f6sungsm\u00f6glichkeiten bei studienspezifischen Problemen, aber auch bei pers\u00f6nlichen Konflikten und Krisen. <\/p>\n\n<p>Der Dienst umfasst professionelle Beratung, Krisenintervention und \u2013 falls erforderlich \u2013 die rasche Vermittlung eines Therapieangebots.<\/p>\n\n<p>Das Angebot wird in Kooperation mit dem Verein f\u00fcr Psychotherapie erm\u00f6glicht und von der \u00d6H Helpline unterst\u00fctzt. Es steht Studierenden der Angewandten ab Mitte November zur Verf\u00fcgung. Die Beratung findet zwei Mal w\u00f6chentlich vor Ort an der Angewandten statt.  <\/p>\n\n<p><strong>Terminvereinbarungen<\/strong> k\u00f6nnen \u00fcber <a href=\"https:\/\/www.etermin.net\/angewandte\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.etermin.net\/angewandte<\/a> oder telefonisch unter +43-1-585-3333 (Montag bis Freitag 9 \u2013 18 Uhr) erfolgen.<br\/>Ort: GCP-023 im HP (Postsparkasse, Eingang Dominikaner Bastei)<br\/>Zeit: Dienstag 10:30 \u2013 12:30 Uhr und Donnerstag 17:30 \u2013 19:30 Uhr <\/p>\n\n<p><strong>In akuten Krisensituationen k\u00f6nnen Studierende sich jederzeit an folgende Stellen wenden:<\/strong><\/p>\n\n<p><strong>24-Stunden-Notfall-Hotlines<\/strong><\/p>\n\n<p> Sozialpsychiatrischer Notdienst: +43-1-31330<br\/>Telefonseelsorge Wien: +43-142<br\/>Frauennotruf: +43-1-71719<br\/>M\u00e4nnernotruf: +43-800-246-247<\/p>\n\n<p><strong>Weitere Angebote<\/strong><\/p>\n\n<p><strong>Psychologische Studierendenberatung<\/strong> Kostenlos f\u00fcr Studierende aller \u00f6sterreichischen Hochschulen. Die Beratung umfasst Themen wie Pr\u00fcfungs\u00e4ngste, Lernschwierigkeiten, Stressbew\u00e4ltigung sowie pers\u00f6nliche Krisen und psychische Belastungen.  <a href=\"https:\/\/www.studierendenberatung.at\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.studierendenberatung.at\/en\/<\/a><\/p>\n\n<p><strong>\u00d6H Helpline<\/strong> Die \u00d6H Helpline bietet Studierenden rund um die Uhr kostenlose und anonyme Beratung bei studienbezogenen, sozialen oder psychischen Problemen.<br\/>Telefonnummer: +43-1-585-3333<br\/><a href=\"https:\/\/www.oeh.ac.at\/en\/helpline\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.oeh.ac.at\/helpline\/<\/a> <\/p>\n\n<p><strong>Rat auf Draht <\/strong>Anonyme, kostenfreie Notrufnummer f\u00fcr junge Erwachsene bis 27 Jahre. Psychologische Soforthilfe rund um die Uhr.<br\/>Telefonnummer: +43-147<br\/><a href=\"https:\/\/www.rataufdraht.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.rataufdraht.at\/<\/a>  <\/p>\n\n<p>Kostenloser und anonymer Online-Chat f\u00fcr Frauen und M\u00e4dchen, die von Gewalt betroffen sind. Bietet auch psychologische Unterst\u00fctzung.  <a href=\"https:\/\/helpchat.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/helpchat.at\/<\/a><\/p>\n\n<p><strong>Frauen-Helpline<\/strong><br\/>Spezielle Beratungsstellen f\u00fcr Frauen<br\/>Telefonnummer: +43-800-222-555<br\/><a href=\"https:\/\/www.frauenhelpline.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.frauenhelpline.at\/<\/a><\/p>\n\n<p>Suchthilfe Wien<br\/>Die Suchthilfe Wien bietet umfassende Unterst\u00fctzung f\u00fcr Menschen mit Suchterkrankungen sowie deren Angeh\u00f6rige, darunter Beratung, Therapie und Hilfestellungen auf dem Weg zur Suchtbew\u00e4ltigung.<br\/>Krisentelefon: +43-1-4000-53799<br\/><a href=\"https:\/\/www.suchthilfe.wien\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.suchthilfe.wien\/<\/a><br\/>Wir freuen uns \u00fcber Ihr Feedback und hei\u00dfen es herzlich willkommen! <a href=\"mailto:sozial@hufak.net\">sozial{at}hufak.net<\/a><br\/><br\/><br\/><br\/>  <a href=\"mailto:nassirou.holik@hufak.net\"><em>{at}<\/em><\/a><a href=\"mailto:sozial@hufak.net\">hufak.net<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die psychologische Beratung bietet allen Studierenden der Angewandten bei Bedarf vertraulich, anonym und kostenfrei Hilfe durch erfahrene Psychotherapeut*innen. Die Beratung unterst\u00fctzt Studierende unmittelbar bei der Suche nach L\u00f6sungsm\u00f6glichkeiten bei studienspezifischen Problemen, aber auch bei pers\u00f6nlichen Konflikten und Krisen. Der Dienst umfasst professionelle Beratung, Krisenintervention und \u2013 falls erforderlich \u2013 die rasche Vermittlung eines Therapieangebots. Das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"wf_page_folders":[30],"class_list":["post-673","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/pages\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/comments?post=673"}],"version-history":[{"count":5,"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/pages\/673\/revisions"}],"predecessor-version":[{"id":678,"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/pages\/673\/revisions\/678"}],"wp:attachment":[{"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/media?parent=673"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/temp.hufak.net\/de\/wp-json\/wp\/v2\/wf_page_folders?post=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}